{"id":2687,"date":"2017-05-31T16:48:20","date_gmt":"2017-05-31T16:48:20","guid":{"rendered":"http:\/\/jsdacores.pt\/front\/?p=2687"},"modified":"2017-06-04T11:13:24","modified_gmt":"2017-06-04T11:13:24","slug":"jsdmadalena-comemora-feriado-com-atividade-de-limpeza-de-costa","status":"publish","type":"post","link":"http:\/\/jsdacores.pt\/front\/news\/jsdmadalena-comemora-feriado-com-atividade-de-limpeza-de-costa\/","title":{"rendered":"JSD\/Madalena comemora feriado com atividade de limpeza de costa"},"content":{"rendered":"<h4>A Juventude Social Democrata da Madalena do Pico, a Calma do Mar e a Tripix Azores ir\u00e3o comemorar o pr\u00f3ximo dia 10 de Junho com uma atividade de limpeza de costa do concelho, nas zonas do Lajido e Cria\u00e7\u00e3o Velha.<\/h4>\n<p>Como explicou o presidente da estrutura local, e vice-presidente regional da JSD\/A\u00e7ores, Andr\u00e9 Soares, a atividade &#8220;junta jovens e for\u00e7as vivas do turismo do concelho com o objetivo comum de melhorar as condi\u00e7\u00f5es de usufruto da orla costeira do concelho&#8221;.<\/p>\n<p>A atividade decorrer\u00e1 no feriado do dia de Portugal, de Cam\u00f5es e das Comunidades Portuguesas a partir das 9H,\u00a0iniciando-se no Solar das Salemas. A participa\u00e7\u00e3o \u00e9 aberta a toda a comunidade, devendo a inscri\u00e7\u00e3o ser feita at\u00e9 dia 08 de Junho pelos contactos disponibilizados pela organiza\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Juventude Social Democrata da Madalena do Pico, a Calma do Mar e a Tripix Azores ir\u00e3o comemorar o pr\u00f3ximo dia 10 de Junho com uma<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":2694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[11],"tags":[],"class_list":["post-2687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/jsdacores.pt\/front\/wp-content\/uploads\/2017\/05\/DSCN0501.jpg?fit=2000%2C1500","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8wvZV-Hl","_links":{"self":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/2687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/comments?post=2687"}],"version-history":[{"count":5,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/2687\/revisions"}],"predecessor-version":[{"id":2725,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/2687\/revisions\/2725"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/media\/2694"}],"wp:attachment":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/media?parent=2687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/categories?post=2687"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/tags?post=2687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}