{"id":3836,"date":"2018-03-06T14:50:27","date_gmt":"2018-03-06T14:50:27","guid":{"rendered":"http:\/\/jsdacores.pt\/front\/?p=3836"},"modified":"2018-03-08T16:25:46","modified_gmt":"2018-03-08T16:25:46","slug":"andre-soares-afirma-que-e-necessario-nutrir-a-ligacao-emocional-que-os-estudantes-acorianos-mantem-com-a-sua-regiao","status":"publish","type":"post","link":"http:\/\/jsdacores.pt\/front\/news\/andre-soares-afirma-que-e-necessario-nutrir-a-ligacao-emocional-que-os-estudantes-acorianos-mantem-com-a-sua-regiao\/","title":{"rendered":"Andr\u00e9 Soares afirma que &#8220;devemos saber converter o carinho dos estudantes deslocados na possibilidade de regresso aos A\u00e7ores&#8221;"},"content":{"rendered":"<h4>O Vice-Presidente da JSD\/A\u00e7ores, Andr\u00e9 Soares, participou no 2\u00ba Encontro Nacional de Estudantes A\u00e7orianos, em Lisboa, onde afirmou que &#8220;a\u00a0juventude espera apenas que, no meio de todas as dificuldades de emprego da nossa regi\u00e3o, o acesso \u00e0s oportunidades seja t\u00e3o livre e transparente quanto aquilo que \u00e9 apregoado&#8221;.<\/h4>\n<p>Para Andr\u00e9 Soares, ele pr\u00f3prio um ex-estudante do Porto e que regressou ao Pico, &#8220;ser estudante a\u00e7oriano deslocado j\u00e1 tem as suas dificuldades inerentes. Se desafiarem a organizar um evento desta din\u00e2mica para estudantes espalhados por todo o pa\u00eds, s\u00f3 mostra todo o esp\u00edrito empreendedor da juventude de que tanto se falou neste encontro&#8221;, deixando os &#8220;calorosos parab\u00e9ns\u00a0\u00e0 Associa\u00e7\u00e3o Nacional de Jovens A\u00e7orianos&#8221;.<\/p>\n<p>&#8220;Ap\u00f3s dois dias de pain\u00e9is e de conv\u00edvio, \u00e9 not\u00f3rio que o estudante a\u00e7oriano nutre um carinho especial pelas suas ilhas. No entanto, h\u00e1 muito a fazer de modo a oferecer as condi\u00e7\u00f5es para que esse carinho se transforme num regresso \u00e0s origens&#8221; afirmou Andr\u00e9 Soares, garantindo que &#8220;a\u00a0JSD compromete-se sempre a defender os interesses e o futuro de toda a juventude a\u00e7oriana, adaptando-se e indo de encontro aos interesses das gera\u00e7\u00f5es que ser\u00e3o o nosso futuro e, que esperamos que vejam em n\u00f3s exatamente essas bandeiras&#8221;.<\/p>\n<p>O Encontro Nacional de Estudantes A\u00e7orianos (ENEAz), na sua segunda edi\u00e7\u00e3o, decorreu este fim-de-semana em Lisboa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Vice-Presidente da JSD\/A\u00e7ores, Andr\u00e9 Soares, participou no 2\u00ba Encontro Nacional de Estudantes A\u00e7orianos, em Lisboa, onde afirmou que &#8220;a\u00a0juventude espera apenas que, no meio de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":3876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[23,11],"tags":[],"class_list":["post-3836","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-emprego","category-news","post_format-post-format-image"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/jsdacores.pt\/front\/wp-content\/uploads\/2018\/03\/28783432_1905481529476659_2461174899520045056_o.jpg?fit=2048%2C1365","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8wvZV-ZS","_links":{"self":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/3836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/comments?post=3836"}],"version-history":[{"count":7,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/3836\/revisions"}],"predecessor-version":[{"id":3866,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/3836\/revisions\/3866"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/media\/3876"}],"wp:attachment":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/media?parent=3836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/categories?post=3836"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/tags?post=3836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}