{"id":4003,"date":"2018-04-06T12:13:24","date_gmt":"2018-04-06T12:13:24","guid":{"rendered":"http:\/\/jsdacores.pt\/front\/?p=4003"},"modified":"2018-04-06T12:15:28","modified_gmt":"2018-04-06T12:15:28","slug":"delegacao-acoriana-ao-xxv-congresso-nacional-composta-por-30-congressistas","status":"publish","type":"post","link":"http:\/\/jsdacores.pt\/front\/news\/delegacao-acoriana-ao-xxv-congresso-nacional-composta-por-30-congressistas\/","title":{"rendered":"Delega\u00e7\u00e3o A\u00e7oriana ao XXV Congresso Nacional composta por 30 congressistas"},"content":{"rendered":"<h4>A delega\u00e7\u00e3o A\u00e7oriana, entre delegados, participantes e observadores, ao XXV Congresso Nacional da Juventude Social Democrata \u00e9 composta por 30 congressistas de quase todos os concelhos A\u00e7orianos.<\/h4>\n<p>S\u00e3o 30 os jovens dos A\u00e7ores que daqui por uma semana representar\u00e3o a estrutura regional na P\u00f3voa de Varzim quando tiver in\u00edcio mais uma reuni\u00e3o do org\u00e3o m\u00e1ximo da estrutura. Como explicou Fl\u00e1vio Soares, Presidente da JSD\/A\u00e7ores, &#8220;entre os delegados eleitos pelas bases e com direito de voto no congresso, os participantes por iner\u00eancia, por estarem a terminar mandato num dos \u00f3rg\u00e3os nacionais, ou os observadores do congresso, consegue-se conjugar uma delega\u00e7\u00e3o representativa de quase todos as ilhas a\u00e7orianas&#8221;.<\/p>\n<p>O XXV Congresso Nacional tem a sua abertura programada para daqui a uma semana, dia 13 de abril,na cidade da P\u00f3voa de Varzim e s\u00f3 termina no domingo, dia 15 de abril, j\u00e1 depois de eleitos os novos \u00f3rg\u00e3os nacionais da estrutura para um mandato de dois anos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A delega\u00e7\u00e3o A\u00e7oriana, entre delegados, participantes e observadores, ao XXV Congresso Nacional da Juventude Social Democrata \u00e9 composta por 30 congressistas de quase todos os concelhos<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":4004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[11],"tags":[],"class_list":["post-4003","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-news","post_format-post-format-image"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/jsdacores.pt\/front\/wp-content\/uploads\/2018\/04\/bandeira-da-jota.jpg?fit=1067%2C800","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8wvZV-12z","_links":{"self":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/4003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/comments?post=4003"}],"version-history":[{"count":3,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/4003\/revisions"}],"predecessor-version":[{"id":4007,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/4003\/revisions\/4007"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/media\/4004"}],"wp:attachment":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/media?parent=4003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/categories?post=4003"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/tags?post=4003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}