{"id":5151,"date":"2019-01-21T11:35:20","date_gmt":"2019-01-21T11:35:20","guid":{"rendered":"http:\/\/jsdacores.pt\/front\/?p=5151"},"modified":"2019-01-21T11:36:24","modified_gmt":"2019-01-21T11:36:24","slug":"xx-congresso-regional-abre-na-proxima-sexta-feira-com-o-futuro-da-estrutura-em-cima-da-mesa","status":"publish","type":"post","link":"http:\/\/jsdacores.pt\/front\/news\/xx-congresso-regional-abre-na-proxima-sexta-feira-com-o-futuro-da-estrutura-em-cima-da-mesa\/","title":{"rendered":"XX Congresso Regional abre na pr\u00f3xima sexta-feira com o futuro da estrutura em cima da mesa"},"content":{"rendered":"<h4>O XX Congresso Regional da JSD\/A\u00e7ores abre na pr\u00f3xima sexta-feira, dia 25 de janeiro, com o futuro da estrutura em cima da mesa, juntando mais de 100 congressistas, entre delegados, participantes e convidados, em S\u00e3o Vicente Ferreira para o debate.<\/h4>\n<p>O caminho que come\u00e7ou com o agendamento da vig\u00e9sima reuni\u00e3o magna da JSD\/A\u00e7ores, na ilha Terceira, est\u00e1 prestes a ter o seu in\u00edcio, com o actual l\u00edder da JSD\/A\u00e7ores, Fl\u00e1vio Soares, recandidato a um novo mandato, depois de j\u00e1 ter apresentar a sua mo\u00e7\u00e3o global de estrat\u00e9gia, sob o lema &#8220;Juntos at\u00e9 \u00e0 Vit\u00f3ria&#8221;.<\/p>\n<p>Durante o decorrer dos tr\u00eas dias de trabalhos, os congressistas ir\u00e3o debater e votar n\u00e3o s\u00f3 a elei\u00e7\u00e3o dos novos \u00f3rg\u00e3os regionais, mas tamb\u00e9m seis mo\u00e7\u00f5es tem\u00e1ticas e uma proposta de revis\u00e3o estatut\u00e1ria (<a href=\"http:\/\/jsdacores.pt\/front\/wp-content\/uploads\/2018\/12\/Livro-Online.pdf\">consultar aqui<\/a>).\u00a0\u00c9 j\u00e1 depois destas vota\u00e7\u00f5es estarem terminadas, que acontece o jantar confer\u00eancia do congresso, com o eurodeputado Paulo Rangel, \u00e0 volta do tema &#8220;Os desafios futuros da UE&#8221;.<\/p>\n<p>A sess\u00e3o de encerramento acontece no domingo, dia 27 de janeiro, com a interven\u00e7\u00e3o do l\u00edder da JSD\/A\u00e7ores, Fl\u00e1vio Soares, do presidente do PSD\/A\u00e7ores, Alexandre Gaud\u00eancio, da l\u00edder nacional da JSD, Margarida Balseiro Lopes e do presidente da JSD\/Madeira, Bruno Melim.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O XX Congresso Regional da JSD\/A\u00e7ores abre na pr\u00f3xima sexta-feira, dia 25 de janeiro, com o futuro da estrutura em cima da mesa, juntando mais de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":5152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"spay_email":"","footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[28,11,31],"tags":[],"class_list":["post-5151","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-destaque","category-news","category-xxicongresso","post_format-post-format-image"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/jsdacores.pt\/front\/wp-content\/uploads\/2019\/01\/17038497_1774240809268458_4106208917147986959_o.jpg?fit=2048%2C1365","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8wvZV-1l5","_links":{"self":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/5151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/comments?post=5151"}],"version-history":[{"count":2,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/5151\/revisions"}],"predecessor-version":[{"id":5154,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/posts\/5151\/revisions\/5154"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/media\/5152"}],"wp:attachment":[{"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/media?parent=5151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/categories?post=5151"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/jsdacores.pt\/front\/wp-json\/wp\/v2\/tags?post=5151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}